{"id":40308,"date":"2024-04-04T10:27:20","date_gmt":"2024-04-04T17:27:20","guid":{"rendered":"https:\/\/truecare.org\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/"},"modified":"2025-10-31T16:04:14","modified_gmt":"2025-10-31T23:04:14","slug":"sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes","status":"publish","type":"post","link":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/","title":{"rendered":"SDBJ nombra a dos l\u00edderes de TrueCare como mujeres influyentes"},"content":{"rendered":"<p><strong>El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50.<\/strong>  Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, l\u00edder cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.<\/p>\n<p>El liderazgo de Tracy ha transformado los resultados de salud de los pacientes de TrueCare. Su dedicaci\u00f3n a la integraci\u00f3n de tecnolog\u00eda avanzada en la atenci\u00f3n m\u00e9dica no solo ha obtenido elogios a nivel nacional, ejemplificado por su Premio a la Colaboraci\u00f3n CHIME, sino que tambi\u00e9n ha logrado mejoras tangibles en la atenci\u00f3n al paciente. Bajo su direcci\u00f3n, TrueCare ha visto una reducci\u00f3n del 58% en los tiempos de resoluci\u00f3n de problemas. A trav\u00e9s de asociaciones estrat\u00e9gicas, encabez\u00f3 los avances en salud digital, incluida la reducci\u00f3n de los tiempos de espera del tel\u00e9fono, un aumento significativo en las tasas activas de MyChart y el lanzamiento de la programaci\u00f3n en l\u00ednea y el autoregistro para los pacientes. Su papel activo en la junta directiva de TI de Sharp HealthCare y como profesora adjunta en la Universidad de Loma Linda consolida su compromiso de dar forma al futuro de la inform\u00e1tica de la atenci\u00f3n m\u00e9dica.<\/p>\n<p>El mandato de la Dra. Sebiane ha estado marcado por una dedicaci\u00f3n inquebrantable a la atenci\u00f3n m\u00e9dica culturalmente sensible. Como costarricense estadounidense de primera generaci\u00f3n, ha mejorado la atenci\u00f3n al paciente para las diversas comunidades de San Diego a trav\u00e9s de su experiencia biling\u00fce y bicultural, abordando las brechas de atenci\u00f3n m\u00e9dica. Su liderazgo llev\u00f3 a la integraci\u00f3n del Cuestionario de Edades y Etapas en los ex\u00e1menes de ni\u00f1o sano, lo que influy\u00f3 en una subvenci\u00f3n de $2 millones de la HRSA para apoyar a las familias que manejan los desaf\u00edos del desarrollo. La colaboraci\u00f3n de la Dra. Sebiane con los dietistas registrados de TrueCare estableci\u00f3 un programa de nutrici\u00f3n en toda la organizaci\u00f3n. Su apoyo a la atenci\u00f3n pedi\u00e1trica especializada, como el Programa de \u00c9xito Acad\u00e9mico de TrueCare para el TDAH y el autismo, ayuda a los pacientes con discapacidades de aprendizaje. Su pasi\u00f3n por las iniciativas de calidad, como las pr\u00e1cticas de inmunizaci\u00f3n informadas sobre el trauma, dio lugar a la adopci\u00f3n de bloqueadores de vacunas. Como defensora cl\u00ednica del reconocimiento del Centro de Salud Amigable con la Lactancia Materna de TrueCare y la expansi\u00f3n de la atenci\u00f3n ginecol\u00f3gica para adolescentes y adultos j\u00f3venes, la Dra. Sebiane no solo ha elevado la continuidad de la atenci\u00f3n sino tambi\u00e9n la salud para todos.<\/p>\n<p>\u00a1Felicitamos a Tracy y al Dr. Sebiane por sus elogios! Estamos muy orgullosos de sus contribuciones para marcar la diferencia en la vida de nuestros pacientes y diversas comunidades.<\/p>\n<p>Para leer el n\u00famero especial del San Diego Business Journal, <a href=\"https:\/\/images.sdbj.com\/wp-content\/uploads\/2024\/03\/SDBJ-Women-of-Influence-50-Over-50-2024.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">lea m\u00e1s&#8230;<\/a><\/p>\n<p><a href=\"https:\/\/images.sdbj.com\/wp-content\/uploads\/2024\/03\/SDBJ-Women-of-Influence-50-Over-50-2024.pdf\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7014 size-medium\" src=\"https:\/\/truecare.org\/wp-content\/uploads\/truecare-read-the-article-svg-buttons-blog-304x54-1.svg\" alt=\"truecare leer el bot\u00f3n del art\u00edculo\" width=\"300\" height=\"57\"><\/a><\/p>\n<h2>Encuentre una ubicaci\u00f3n de TrueCare:<\/h2>\n<p><a href=\"https:\/\/truecare.org\/es\/ubicaciones\/\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-7014 size-medium\" src=\"https:\/\/truecare.org\/wp-content\/uploads\/truecare-schedule-find-a-location-svg-buttons-blog-304x54-1.svg\" alt=\"truecare encontrar un bot\u00f3n de ubicaci\u00f3n\" width=\"300\" height=\"57\"><\/a><\/p>\n<span class=\"et_bloom_bottom_trigger\"><\/span>","protected":false},"excerpt":{"rendered":"<p>El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":40306,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[125],"tags":[],"class_list":["post-40308","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dos l\u00edderes de TrueCare nombradas mujeres influyentes | Cuidado verdadero<\/title>\n<meta name=\"description\" content=\"El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, directora cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dos l\u00edderes de TrueCare nombradas mujeres influyentes | Cuidado verdadero\" \/>\n<meta property=\"og:description\" content=\"El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, directora cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.\" \/>\n<meta property=\"og:site_name\" content=\"TrueCare\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/healthtruecare\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-04T17:27:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-31T23:04:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/truecare.org\/wp-content\/uploads\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shannon Mbuthia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@healthtruecare\" \/>\n<meta name=\"twitter:site\" content=\"@healthtruecare\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Shannon Mbuthia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/\"},\"author\":{\"name\":\"Shannon Mbuthia\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#\\\/schema\\\/person\\\/d7b523d5dae4e25b689b6b9cd100f742\"},\"headline\":\"SDBJ nombra a dos l\u00edderes de TrueCare como mujeres influyentes\",\"datePublished\":\"2024-04-04T17:27:20+00:00\",\"dateModified\":\"2025-10-31T23:04:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/\"},\"wordCount\":520,\"publisher\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truecare.org\\\/wp-content\\\/uploads\\\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg\",\"articleSection\":[\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/\",\"url\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/\",\"name\":\"Dos l\u00edderes de TrueCare nombradas mujeres influyentes | Cuidado verdadero\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/truecare.org\\\/wp-content\\\/uploads\\\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg\",\"datePublished\":\"2024-04-04T17:27:20+00:00\",\"dateModified\":\"2025-10-31T23:04:14+00:00\",\"description\":\"El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, directora cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/truecare.org\\\/wp-content\\\/uploads\\\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg\",\"contentUrl\":\"https:\\\/\\\/truecare.org\\\/wp-content\\\/uploads\\\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg\",\"width\":700,\"height\":466,\"caption\":\"Tracy Elmer de TrueCare y la Dra. Maria Sebiane Mujeres influyentes 2024 del San Diego Business Journal: 50 sobre 50\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/blog\\\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/truecare.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SDBJ nombra a dos l\u00edderes de TrueCare como mujeres influyentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/truecare.org\\\/es\\\/\",\"name\":\"TrueCare\",\"description\":\"Health inside. Welcome in.\",\"publisher\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/truecare.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#organization\",\"name\":\"TrueCare\",\"url\":\"https:\\\/\\\/truecare.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/truecare.org\\\/wp-content\\\/uploads\\\/truecare-logo-header-205x45-1.svg\",\"contentUrl\":\"https:\\\/\\\/truecare.org\\\/wp-content\\\/uploads\\\/truecare-logo-header-205x45-1.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"TrueCare\"},\"image\":{\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/healthtruecare\",\"https:\\\/\\\/x.com\\\/healthtruecare\",\"https:\\\/\\\/www.instagram.com\\\/truecare.health\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/health-truecare\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UClN83htaiuzCzfzdikXPCTw\",\"https:\\\/\\\/www.pinterest.com\\\/healthtruecare\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/truecare.org\\\/es\\\/#\\\/schema\\\/person\\\/d7b523d5dae4e25b689b6b9cd100f742\",\"name\":\"Shannon Mbuthia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2157d558280f5e0ec14b3edabfe71f345d8d1dfa9951c7d370868d364f7a8b8b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2157d558280f5e0ec14b3edabfe71f345d8d1dfa9951c7d370868d364f7a8b8b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2157d558280f5e0ec14b3edabfe71f345d8d1dfa9951c7d370868d364f7a8b8b?s=96&d=mm&r=g\",\"caption\":\"Shannon Mbuthia\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dos l\u00edderes de TrueCare nombradas mujeres influyentes | Cuidado verdadero","description":"El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, directora cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/","og_locale":"es_ES","og_type":"article","og_title":"Dos l\u00edderes de TrueCare nombradas mujeres influyentes | Cuidado verdadero","og_description":"El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, directora cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.","og_site_name":"TrueCare","article_publisher":"https:\/\/www.facebook.com\/healthtruecare","article_published_time":"2024-04-04T17:27:20+00:00","article_modified_time":"2025-10-31T23:04:14+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg","type":"image\/jpeg"}],"author":"Shannon Mbuthia","twitter_card":"summary_large_image","twitter_creator":"@healthtruecare","twitter_site":"@healthtruecare","twitter_misc":{"Escrito por":"Shannon Mbuthia","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#article","isPartOf":{"@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/"},"author":{"name":"Shannon Mbuthia","@id":"https:\/\/truecare.org\/es\/#\/schema\/person\/d7b523d5dae4e25b689b6b9cd100f742"},"headline":"SDBJ nombra a dos l\u00edderes de TrueCare como mujeres influyentes","datePublished":"2024-04-04T17:27:20+00:00","dateModified":"2025-10-31T23:04:14+00:00","mainEntityOfPage":{"@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/"},"wordCount":520,"publisher":{"@id":"https:\/\/truecare.org\/es\/#organization"},"image":{"@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#primaryimage"},"thumbnailUrl":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg","articleSection":["Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/","url":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/","name":"Dos l\u00edderes de TrueCare nombradas mujeres influyentes | Cuidado verdadero","isPartOf":{"@id":"https:\/\/truecare.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#primaryimage"},"image":{"@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#primaryimage"},"thumbnailUrl":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg","datePublished":"2024-04-04T17:27:20+00:00","dateModified":"2025-10-31T23:04:14+00:00","description":"El San Diego Business Journal ha honrado a dos l\u00edderes de TrueCare como Mujeres de Influencia 2024: 50 sobre 50. Tracy Elmer, directora de innovaci\u00f3n, y la Dra. Maria Sebiane, directora cl\u00ednica de TrueCare San Marcos Pediatrics, fueron reconocidas por su liderazgo excepcional.","breadcrumb":{"@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#primaryimage","url":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg","contentUrl":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-news-sdbj-honoree-tracy-elmer-maria-sebiane-featured-image-blog-700x466-1.jpg","width":700,"height":466,"caption":"Tracy Elmer de TrueCare y la Dra. Maria Sebiane Mujeres influyentes 2024 del San Diego Business Journal: 50 sobre 50"},{"@type":"BreadcrumbList","@id":"https:\/\/truecare.org\/es\/blog\/sdbj-nombra-a-dos-lideres-de-truecare-como-mujeres-influyentes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/truecare.org\/es\/"},{"@type":"ListItem","position":2,"name":"SDBJ nombra a dos l\u00edderes de TrueCare como mujeres influyentes"}]},{"@type":"WebSite","@id":"https:\/\/truecare.org\/es\/#website","url":"https:\/\/truecare.org\/es\/","name":"TrueCare","description":"Health inside. Welcome in.","publisher":{"@id":"https:\/\/truecare.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/truecare.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/truecare.org\/es\/#organization","name":"TrueCare","url":"https:\/\/truecare.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/truecare.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-logo-header-205x45-1.svg","contentUrl":"https:\/\/truecare.org\/wp-content\/uploads\/truecare-logo-header-205x45-1.svg","width":"1024","height":"1024","caption":"TrueCare"},"image":{"@id":"https:\/\/truecare.org\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/healthtruecare","https:\/\/x.com\/healthtruecare","https:\/\/www.instagram.com\/truecare.health\/","https:\/\/www.linkedin.com\/company\/health-truecare\/","https:\/\/www.youtube.com\/channel\/UClN83htaiuzCzfzdikXPCTw","https:\/\/www.pinterest.com\/healthtruecare"]},{"@type":"Person","@id":"https:\/\/truecare.org\/es\/#\/schema\/person\/d7b523d5dae4e25b689b6b9cd100f742","name":"Shannon Mbuthia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/2157d558280f5e0ec14b3edabfe71f345d8d1dfa9951c7d370868d364f7a8b8b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2157d558280f5e0ec14b3edabfe71f345d8d1dfa9951c7d370868d364f7a8b8b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2157d558280f5e0ec14b3edabfe71f345d8d1dfa9951c7d370868d364f7a8b8b?s=96&d=mm&r=g","caption":"Shannon Mbuthia"}}]}},"_links":{"self":[{"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/posts\/40308","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/comments?post=40308"}],"version-history":[{"count":2,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/posts\/40308\/revisions"}],"predecessor-version":[{"id":48347,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/posts\/40308\/revisions\/48347"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/media\/40306"}],"wp:attachment":[{"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/media?parent=40308"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/categories?post=40308"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/truecare.org\/es\/wp-json\/wp\/v2\/tags?post=40308"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}